{"id":6624,"date":"2025-07-11T09:27:28","date_gmt":"2025-07-11T13:27:28","guid":{"rendered":"https:\/\/suanoticiaaqui.com.br\/news\/?p=6624"},"modified":"2025-07-11T09:27:28","modified_gmt":"2025-07-11T13:27:28","slug":"dois-homens-sao-presos-pela-prf-com-4115-quilos-de-maconha-em-ms","status":"publish","type":"post","link":"https:\/\/suanoticiaaqui.com.br\/news\/2025\/07\/11\/dois-homens-sao-presos-pela-prf-com-4115-quilos-de-maconha-em-ms\/","title":{"rendered":"Dois homens s\u00e3o presos pela PRF com 411,5 quilos de maconha em MS"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li>\u00a0por Ligado na Noticia<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Dois homens foram presos pela PRF (Pol\u00edcia Rodovi\u00e1ria Federal) na tarde desta quarta-feira (9\/7), transportando 411,5 quilos de maconha, em Ivinhema. A equipe deu ordem de parada ao motorista de um ve\u00edculo VW Voyage, ocupado por dois homens, por\u00e9m, n\u00e3o foi obedecida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s alguns quil\u00f4metros, os autores abandonaram o carro, o jogando em uma valeta, e tentaram fugir a p\u00e9, no entanto, um deles acabou detido e identificado pelos PRFs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No ve\u00edculo, al\u00e9m dos mais de 411 quilos de maconha, foram apreendidos 1,6 quilo de skunk.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O homem disse ser morador de Belo Horizonte (MG), e que junto com o comparsa, levaria a droga de Coronel Sapucaia at\u00e9 a cidade de S\u00e3o Paulo (SP) e que o veiculo usado para o transporte do il\u00edcito era locado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s dilig\u00eancias, o outro suspeito foi localizado \u00e0s margens da rodovia e identificado. Os envolvidos e a ocorr\u00eancia foram encaminhados para a PC (Pol\u00edcia Civil) de Ivinhema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dois homens foram presos pela PRF (Pol\u00edcia Rodovi\u00e1ria Federal) na tarde desta quarta-feira (9\/7), transportando 411,5 quilos de maconha, em&hellip;<\/p>\n","protected":false},"author":1,"featured_media":6625,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6624","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts\/6624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/comments?post=6624"}],"version-history":[{"count":1,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts\/6624\/revisions"}],"predecessor-version":[{"id":6626,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts\/6624\/revisions\/6626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/media\/6625"}],"wp:attachment":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/media?parent=6624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/categories?post=6624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/tags?post=6624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}