{"id":6826,"date":"2025-07-21T15:29:39","date_gmt":"2025-07-21T19:29:39","guid":{"rendered":"https:\/\/suanoticiaaqui.com.br\/news\/?p=6826"},"modified":"2025-07-21T15:29:39","modified_gmt":"2025-07-21T19:29:39","slug":"farmacia-de-fachada-em-dourados-e-alvo-de-investigacao-em-fraude-nacional-contra-programa-federal","status":"publish","type":"post","link":"https:\/\/suanoticiaaqui.com.br\/news\/2025\/07\/21\/farmacia-de-fachada-em-dourados-e-alvo-de-investigacao-em-fraude-nacional-contra-programa-federal\/","title":{"rendered":"Farm\u00e1cia de fachada em Dourados \u00e9 alvo de investiga\u00e7\u00e3o em fraude nacional contra programa federal"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li>por Luiz Guilherme<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Farm\u00e1cia \u201cfantasma\u201d de Dourados est\u00e1 entre os estabelecimentos investigados pela PF (Pol\u00edcia Federal) que apura envolvimento em esquema criminoso que desviou cerca de R$ 40 milh\u00f5es do programa do governo federal Farm\u00e1cia Popular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neste domingo (21\/7), a den\u00fancia foi revelada em reportagem do Fant\u00e1stico, da TV Globo, e aponta que o dinheiro p\u00fablico foi usado para \u201clavar\u201d recursos do tr\u00e1fico internacional de drogas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As redes de farm\u00e1cias, segundo a Pol\u00edcia Federal, operavam em v\u00e1rios estados do Brasil, utilizando CPFs (Cadastro de Pessoa F\u00edsica) e endere\u00e7os de pessoas inocentes para simular venda de medicamentos. A fraude envolvia tamb\u00e9m a compra e venda de CNPJs em nome de \u201claranjas\u201d e usava o sistema do programa para emitir cobran\u00e7as fraudulentas ao SUS (Sistema \u00danico de Sa\u00fade).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>In\u00edcio das investiga\u00e7\u00f5es<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As investiga\u00e7\u00f5es tiveram in\u00edcio depois da apreens\u00e3o de 191 quilos de drogas em Luzi\u00e2nia (GO), no entanto, o esquema se revelou muito maior, com conex\u00f5es em Goi\u00e1s, Mato Grosso do Sul, Minas Gerais, Pernambuco, S\u00e3o Paulo e Rio Grande do Sul. Entre os nomes citados est\u00e1 o de Fernando Batista da Silva, conhecido como \u201cFernando Piolho\u201d, apontado como l\u00edder da organiza\u00e7\u00e3o criminosa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a PF, Fernando usava o nome da filha para abrir empresas, e teria liga\u00e7\u00f5es com o Comando Vermelho e o Cl\u00e3 Cisneros, organiza\u00e7\u00e3o criminosa peruana ligada a laborat\u00f3rios de coca\u00edna. A defesa do suspeito nega o envolvimento de seu cliente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os trabalhos investigativos revelaram ainda que algumas dessas farm\u00e1cias que, se quer existiam fisicamente, estavam registradas em terrenos baldios, como uma localizada em \u00c1guas Lindas (GO), onde dois endere\u00e7os fantasmas teriam recebido quase R$ 500 mil do Farm\u00e1cia Popular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em outro exemplo, uma farm\u00e1cia que deveria funcionar em Campo Belo (MG) foi associada a uma empregada dom\u00e9stica que consta como dona de cinco drogarias em diferentes estados e movimentou cerca de meio milh\u00e3o de reais. O nome dela tamb\u00e9m aparece vinculado \u00e0 empresa Drogaria PHS, que teria feito saques indevidos usando o CPF de um dentista de Sumar\u00e9 (SP), que nunca foi diab\u00e9tico, mas teve a retirada de at\u00e9 20 caixas de insulina por m\u00eas registrada em seu nome.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Pol\u00edcia Federal apura ainda se os valores desviados de farm\u00e1cias como a de Dourados foram repassados \u00e0 organiza\u00e7\u00e3o comandada por \u201cFernando Piolho\u201d, que teria usado o programa como fonte de financiamento do tr\u00e1fico internacional de drogas, especialmente na fronteira com Bol\u00edvia e Peru.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Atualmente, cerca de 160 mil CPFs foram identificados como usados indevidamente pelo grupo, em uma rede que contava com pelo menos 148 farm\u00e1cias reais ou fantasmas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Farm\u00e1cia \u201cfantasma\u201d de Dourados est\u00e1 entre os estabelecimentos investigados pela PF (Pol\u00edcia Federal) que apura envolvimento em esquema criminoso que&hellip;<\/p>\n","protected":false},"author":1,"featured_media":6827,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts\/6826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/comments?post=6826"}],"version-history":[{"count":1,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts\/6826\/revisions"}],"predecessor-version":[{"id":6828,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts\/6826\/revisions\/6828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/media\/6827"}],"wp:attachment":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/media?parent=6826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/categories?post=6826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/tags?post=6826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}