{"id":6922,"date":"2025-07-24T17:14:22","date_gmt":"2025-07-24T21:14:22","guid":{"rendered":"https:\/\/suanoticiaaqui.com.br\/news\/?p=6922"},"modified":"2025-07-24T17:14:22","modified_gmt":"2025-07-24T21:14:22","slug":"policia-prende-mandante-de-assalto-em-condominio-de-luxo-na-fronteira","status":"publish","type":"post","link":"https:\/\/suanoticiaaqui.com.br\/news\/2025\/07\/24\/policia-prende-mandante-de-assalto-em-condominio-de-luxo-na-fronteira\/","title":{"rendered":"Pol\u00edcia prende mandante de assalto em condom\u00ednio de luxo na fronteira"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li>por Luiz Guilherme<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">A Pol\u00edcia Civil de Ponta Por\u00e3 prendeu na noite de ontem (23), Nelson Shinichi Motoyama Kita, apontado como mandante de um crime de roubo qualificado, sequestro e extors\u00e3o ocorrido na manh\u00e3 de segunda-feira (21). A v\u00edtima foi uma fam\u00edlia da cidade. O caso envolveu viol\u00eancia armada e tentativa de extors\u00e3o por transfer\u00eancia banc\u00e1ria via PIX no valor de R$ 60 mil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O crime resultou no roubo de um ve\u00edculo da fam\u00edlia, que mais tarde foi localizado abandonado nas proximidades do Aeroporto Internacional. Investiga\u00e7\u00f5es indicam que Nelson Kita conheceu uma das v\u00edtimas em uma academia local e, durante os treinos, obteve informa\u00e7\u00f5es sobre sua situa\u00e7\u00e3o financeira, o que teria motivado e facilitado o planejamento do ataque.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na manh\u00e3 do dia 23, a Primeira Delegacia de Pol\u00edcia, com o apoio da Pol\u00edcia Penal e da Pol\u00edcia Militar, efetuou as pris\u00f5es de Washington Pereira da Silva, Andr\u00e9 Carvalho da Rocha e Nilson Duarte Miguel. O grupo agiu em conjunto com \u00c9der Jaques Miguel, de 37 anos, que permanece foragido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo a Pol\u00edcia, os quatro invadiram a resid\u00eancia do casal armados, inclusive com um fuzil, e fizeram amea\u00e7as exigindo a transfer\u00eancia do valor solicitado. A a\u00e7\u00e3o foi caracterizada como extors\u00e3o mediante sequestro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com base nas provas reunidas, a Justi\u00e7a expediu mandados de pris\u00e3o tempor\u00e1ria e de busca domiciliar contra Kita e \u00c9der Jaques. Apenas Kita foi localizado e preso. Durante as dilig\u00eancias, as for\u00e7as de seguran\u00e7a apreenderam armas \u2014 incluindo o fuzil utilizado no crime \u2014 entorpecentes e parte do dinheiro extorquido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agora, as autoridades concentram esfor\u00e7os na captura de \u00c9der Jaques Miguel, que conseguiu escapar do cerco policial. Ele \u00e9 considerado foragido e qualquer informa\u00e7\u00e3o sobre seu paradeiro pode se<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Civil de Ponta Por\u00e3 prendeu na noite de ontem (23), Nelson Shinichi Motoyama Kita, apontado como mandante de&hellip;<\/p>\n","protected":false},"author":1,"featured_media":6923,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts\/6922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/comments?post=6922"}],"version-history":[{"count":1,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts\/6922\/revisions"}],"predecessor-version":[{"id":6924,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts\/6922\/revisions\/6924"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/media\/6923"}],"wp:attachment":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/media?parent=6922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/categories?post=6922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/tags?post=6922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}