{"id":7103,"date":"2025-07-30T18:55:33","date_gmt":"2025-07-30T22:55:33","guid":{"rendered":"https:\/\/suanoticiaaqui.com.br\/news\/?p=7103"},"modified":"2025-07-30T18:55:33","modified_gmt":"2025-07-30T22:55:33","slug":"operacao-contra-estupro-coletivo-prende-2-e-apreende-5-adolescentes-em-ms","status":"publish","type":"post","link":"https:\/\/suanoticiaaqui.com.br\/news\/2025\/07\/30\/operacao-contra-estupro-coletivo-prende-2-e-apreende-5-adolescentes-em-ms\/","title":{"rendered":"Opera\u00e7\u00e3o contra estupro coletivo prende 2 e apreende 5 adolescentes em MS"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li>por Luiz Guilherme<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Na manh\u00e3 desta quarta-feira (30\/7), a PC (Pol\u00edcia Civil) deflagrou em \u00c1gua Clara, a opera\u00e7\u00e3o &#8220;Asmodeus&#8221; contra um estupro coletivo. Foram cumpridos sete mandados, sendo dois de pris\u00e3o e cinco de apreens\u00e3o contra adolescentes envolvidos no crimes.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os menores foram encaminhados para interna\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conforme a pol\u00edcia, as ordens judiciais foram expedidas pela Justi\u00e7a Estadual ap\u00f3s a investiga\u00e7\u00e3o da delegacia de \u00c1gua Clara, que apurou a pr\u00e1tica do crime e ato infracional de estupro de vulner\u00e1vel coletivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nome da opera\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O nome da opera\u00e7\u00e3o, \u201cAsmodeus\u201d, faz refer\u00eancia a um dem\u00f4nio associado \u00e0 lux\u00faria, desejo e corrup\u00e7\u00e3o, al\u00e9m de tenta\u00e7\u00f5es relacionadas ao prazer e ao pecado, simbolizando a natureza hedionda dos crimes investigados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na manh\u00e3 desta quarta-feira (30\/7), a PC (Pol\u00edcia Civil) deflagrou em \u00c1gua Clara, a opera\u00e7\u00e3o &#8220;Asmodeus&#8221; contra um estupro coletivo.&hellip;<\/p>\n","protected":false},"author":1,"featured_media":7104,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts\/7103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/comments?post=7103"}],"version-history":[{"count":1,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts\/7103\/revisions"}],"predecessor-version":[{"id":7105,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts\/7103\/revisions\/7105"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/media\/7104"}],"wp:attachment":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/media?parent=7103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/categories?post=7103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/tags?post=7103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}