{"id":8881,"date":"2025-10-11T10:59:59","date_gmt":"2025-10-11T14:59:59","guid":{"rendered":"https:\/\/suanoticiaaqui.com.br\/news\/?p=8881"},"modified":"2025-10-11T10:59:59","modified_gmt":"2025-10-11T14:59:59","slug":"policia-civil-e-militar-prendem-suspeito-e-apreendem-armas-e-municoes-em-itapora","status":"publish","type":"post","link":"https:\/\/suanoticiaaqui.com.br\/news\/2025\/10\/11\/policia-civil-e-militar-prendem-suspeito-e-apreendem-armas-e-municoes-em-itapora\/","title":{"rendered":"POL\u00cdCIA CIVIL E MILITAR PRENDEM SUSPEITO E APREENDEM ARMAS E MUNI\u00c7\u00d5ES EM ITAPOR\u00c3"},"content":{"rendered":"\n<p>Foto Divulga\u00e7\u00e3o PM\/PC<\/p>\n\n\n\n<p>por Fabio Correia<\/p>\n\n\n\n<p><strong>A\u00e7\u00e3o conjunta leva \u00e0 pris\u00e3o de homem que amea\u00e7ou v\u00edtima e policial<\/strong>.<\/p>\n\n\n\n<p>A Pol\u00edcia Civil, em uma opera\u00e7\u00e3o conjunta com a Pol\u00edcia Militar, realizou a pris\u00e3o de um indiv\u00edduo e apreendeu duas armas de fogo municiadas na cidade de Itapor\u00e3. A a\u00e7\u00e3o \u00e9 resultado de uma investiga\u00e7\u00e3o iniciada ap\u00f3s um incidente de amea\u00e7a.<\/p>\n\n\n\n<p><strong>O caso<\/strong><\/p>\n\n\n\n<p>H\u00e1 algumas semanas, um caso de amea\u00e7a foi registrado envolvendo um desacordo comercial na negocia\u00e7\u00e3o de ve\u00edculos. A v\u00edtima relatou que um indiv\u00edduo, ap\u00f3s o fracasso do neg\u00f3cio, a amea\u00e7ou com uma arma de fogo.<\/p>\n\n\n\n<p>Ao ser acionada, a Pol\u00edcia Militar enviou uma equipe para abordar o suspeito. No entanto, ele se evadiu e chegou a apontar a arma para um dos policiais.<\/p>\n\n\n\n<p><strong>Busca e apreens\u00e3o<\/strong><\/p>\n\n\n\n<p>Diante dos fatos, o delegado solicitou um mandado de busca e apreens\u00e3o domiciliar para a resid\u00eancia do suspeito, que foi autorizado pela Justi\u00e7a ap\u00f3s parecer favor\u00e1vel do Minist\u00e9rio P\u00fablico.<\/p>\n\n\n\n<p>Na resid\u00eancia, as equipes de seguran\u00e7a encontraram as duas armas de fogo municiadas. O indiv\u00edduo foi preso em flagrante e responder\u00e1 pelos crimes cometidos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto Divulga\u00e7\u00e3o PM\/PC por Fabio Correia A\u00e7\u00e3o conjunta leva \u00e0 pris\u00e3o de homem que amea\u00e7ou v\u00edtima e policial. A Pol\u00edcia&hellip;<\/p>\n","protected":false},"author":1,"featured_media":8882,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8881","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts\/8881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/comments?post=8881"}],"version-history":[{"count":1,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts\/8881\/revisions"}],"predecessor-version":[{"id":8883,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts\/8881\/revisions\/8883"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/media\/8882"}],"wp:attachment":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/media?parent=8881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/categories?post=8881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/tags?post=8881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}