{"id":8921,"date":"2025-10-24T18:04:05","date_gmt":"2025-10-24T22:04:05","guid":{"rendered":"https:\/\/suanoticiaaqui.com.br\/news\/?p=8921"},"modified":"2025-10-24T18:04:05","modified_gmt":"2025-10-24T22:04:05","slug":"homem-e-preso-apos-tentativa-de-homicidio-no-estrela-pora","status":"publish","type":"post","link":"https:\/\/suanoticiaaqui.com.br\/news\/2025\/10\/24\/homem-e-preso-apos-tentativa-de-homicidio-no-estrela-pora\/","title":{"rendered":"Homem \u00e9 preso ap\u00f3s tentativa de homic\u00eddio no Estrela Por\u00e3"},"content":{"rendered":"\n<p>Autor chegando \u00e0 sede do SIG; Foto: Sidnei Bronka\/Ligado Na Not\u00edcia\u00a0<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00a0Sidnei Bronka<\/li>\n<\/ul>\n\n\n\n<p>Policiais do SIG (Setor de Investiga\u00e7\u00f5es Gerais) prenderam nesta quinta-feira (23\/10), Juan Daniel Linares Gonz\u00e1lez, de 29 anos, venezuelano e morador no Bairro Estrela Por\u00e3, em Dourados. Ele \u00e9 apontado como o piloto da motocicleta usada na tentativa de homic\u00eddio contra Guilherme Brites Castilho, de 25, ocorrida nesta semana na Rua Projetada D.<\/p>\n\n\n\n<p>De acordo com as informa\u00e7\u00f5es apuradas, Guilherme foi atingido por tr\u00eas disparos de arma de fogo e segue internado em estado grave na UTI do Hospital da Vida.<\/p>\n\n\n\n<p>Mesmo ap\u00f3s a pris\u00e3o, Juan nega envolvimento no crime. No entanto, conforme os investigadores, h\u00e1 fortes provas que indicam sua participa\u00e7\u00e3o direta no ataque. As evid\u00eancias, segundo o SIG, confirmam que ele conduzia a motocicleta usada na a\u00e7\u00e3o.<\/p>\n\n\n\n<p>As investiga\u00e7\u00f5es apontam ainda que o crime foi encomendado de dentro de um pres\u00eddio de Campo Grande e teria como alvo outra pessoa, n\u00e3o Guilherme. Os criminosos teriam \u201cerrado o alvo\u201d, executando o atentado contra a v\u00edtima errada.<\/p>\n\n\n\n<p>A motiva\u00e7\u00e3o estaria ligada a disputas entre fac\u00e7\u00f5es criminosas, conforme levantado pela pol\u00edcia. O nome do verdadeiro alvo e outros detalhes sobre a ordem de execu\u00e7\u00e3o n\u00e3o foram divulgados para n\u00e3o comprometer o andamento das investiga\u00e7\u00f5es.<\/p>\n\n\n\n<p>O caso segue sendo investigado pelo SIG de Dourados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Autor chegando \u00e0 sede do SIG; Foto: Sidnei Bronka\/Ligado Na Not\u00edcia\u00a0 Policiais do SIG (Setor de Investiga\u00e7\u00f5es Gerais) prenderam nesta&hellip;<\/p>\n","protected":false},"author":1,"featured_media":8922,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8921","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts\/8921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/comments?post=8921"}],"version-history":[{"count":1,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts\/8921\/revisions"}],"predecessor-version":[{"id":8923,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts\/8921\/revisions\/8923"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/media\/8922"}],"wp:attachment":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/media?parent=8921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/categories?post=8921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/tags?post=8921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}