{"id":9213,"date":"2026-03-03T14:35:14","date_gmt":"2026-03-03T18:35:14","guid":{"rendered":"https:\/\/suanoticiaaqui.com.br\/news\/?p=9213"},"modified":"2026-03-03T14:35:14","modified_gmt":"2026-03-03T18:35:14","slug":"prospera-ms-chega-a-dourados-com-feira-da-agricultura-familiar-gastronomia-e-shows","status":"publish","type":"post","link":"https:\/\/suanoticiaaqui.com.br\/news\/2026\/03\/03\/prospera-ms-chega-a-dourados-com-feira-da-agricultura-familiar-gastronomia-e-shows\/","title":{"rendered":"Prospera MS chega a Dourados com feira da agricultura familiar, gastronomia e shows"},"content":{"rendered":"\n<p>Evento ser\u00e1 realizado no Centro de Conven\u00e7\u00f5es localizado na entrada do bairro parque Alvorada &#8211; Foto: Arquivo<br><\/p>\n\n\n\n<p>Evento acontece de 5 a 8 de mar\u00e7o no Centro de Conven\u00e7\u00f5es e re\u00fane produtores rurais, chefs renomados e atra\u00e7\u00f5es nacionais<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>por Dourados Agora<\/li>\n<\/ul>\n\n\n\n<p>A Feira de Agricultura Familiar \u2013 Projeto Prospera MS-, acontece em Dourados, no per\u00edodo de 05 a 08 de mar\u00e7o de 2026, no Centro de Conven\u00e7\u00f5es Ant\u00f4nio Tonani, com incentivo a agricultura familiar, promo\u00e7\u00e3o de cultura e gastronomia regional.&nbsp; A iniciativa \u00e9 promovida pelo Instituto de Desenvolvimento Socioambiental, Minist\u00e9rio do Desenvolvimento Agr\u00e1rio e Agricultura Familiar, Governo Federal e apoio da Prefeitura de Dourados.<\/p>\n\n\n\n<p>O evento trar\u00e1 diversas atra\u00e7\u00f5es para p\u00fablicos de todas as idades,&nbsp; reunindo a\u00e7\u00f5es como a Cozinha Show com degusta\u00e7\u00f5es, oficinas de capacita\u00e7\u00e3o, al\u00e9m de atividades culturais e art\u00edsticas que fortalecem a identidade e o patrim\u00f4nio cultural local. Shows com Maria Cecilia &amp; Rodolfo, Talles &amp; Rafael e Talles &amp; Fred &amp; Victor far\u00e3o parte da programa\u00e7\u00e3o, envolvendo o grande p\u00fablico com can\u00e7\u00f5es bastante conhecidas no cen\u00e1rio musical.&nbsp;<\/p>\n\n\n\n<p>Produtores rurais de Dourados v\u00e3o expor produtos frescos diversos e ter\u00e3o a oportunidade de participa\u00e7\u00e3o de um momento de interc\u00e2mbio, e troca de experi\u00eancia com produtores de outros estados.&nbsp; Destaque para um dos diferenciais do evento que \u00e9 a Cozinha Show, um palco onde chefs reconhecidos da gastronomia brasileira preparam pratos ao vivo com ingredientes selecionados da agricultura local, evidenciando sabor, qualidade e origem.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a class=\"gallery-item\" href=\"https:\/\/douradosagora.com.br\/media\/editorjs\/whatsapp_image_2026_03_02_at_09_1772541243,3677.jpg\"><img decoding=\"async\" src=\"https:\/\/douradosagora.com.br\/media\/editorjs\/whatsapp_image_2026_03_02_at_09_1772541243,3677.jpg\" alt=\"\"\/><\/a><figcaption class=\"wp-element-caption\">Gastronomia com a Cozinha Show \u00e9 um dos pontos altos do evento, unindo sabor e regionalidade. Foto: Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>O momento une gastronomia e regionalidade. No Cozinha Infantil, o momento ser\u00e1 voltado para crian\u00e7as, com receitas simples e prezando pelo entretenimento e desenvolvimento dos envolvidos. Outras edi\u00e7\u00f5es j\u00e1 foram realizadas nos munic\u00edpios de Aquidauana, Navira\u00ed, Coxim, Jardim, Ponta Por\u00e3, Corumb\u00e1, Campo Grande e agora a a\u00e7\u00e3o chega \u00e0 Dourados se consolidando como uma grande vitrine da produ\u00e7\u00e3o rural sul-mato-grossense.<\/p>\n\n\n\n<p>Cabe destacar que a iniciativa foi idealizada pela Senadora Soraya Thronicke e representa uma proposta inovadora e transformadora para o fortalecimento da agricultura no Estado de Mato Grosso do Sul, envolvendo fam\u00edlias em um momento leve e agrad\u00e1vel.&nbsp;<\/p>\n\n\n\n<p>Veja a programa\u00e7\u00e3o completa do Prospera MS em Dourados:&nbsp;<\/p>\n\n\n\n<p>Quinta-feira (05 de mar\u00e7o)<br>\u00b7 16h00: Abertura.<br>\u00b7 16h30: Cozinha Infantil.<br>\u00b7 18h00: Aula Show.<br>\u00b7 19h30: Cozinha Show.<br>\u00b7 21h30: Show no Palco Principal com Maria Cecilia &amp; Rodolfo.<\/p>\n\n\n\n<p>Sexta-feira (06 de mar\u00e7o)<br>\u00b7 16h00: Abertura.<br>\u00b7 16h30: Cozinha Infantil.<br>\u00b7 18h00: Aula Show.<br>\u00b7 19h30: Cozinha Show.<br>\u00b7 21h15: Show Prospera com Talles &amp; Rafael.<\/p>\n\n\n\n<p>S\u00e1bado (07 de mar\u00e7o)<br>\u00b7 11h00: Abertura e Programa \u201cO Povo na TV\u201d ao vivo com Tat\u00e1 Marques.<br>\u00b7 14h00: Cozinha Infantil.<br>\u00b7 17h00: Aula Show.<br>\u00b7 20h00: Cozinha Show.<br>\u00b7 21h30: Show Prospera com Fred &amp; Victor.<\/p>\n\n\n\n<p>Domingo (08 de mar\u00e7o)<br>\u00b7 12h00: Abertura.<br>\u00b7 14h00: Cozinha Infantil.<br>\u00b7 17h00: Aula Show.<br>\u00b7 19h00: Cozinha Show.<br>\u00b7 21h30: Encerramento<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a class=\"gallery-item\" href=\"https:\/\/douradosagora.com.br\/media\/editorjs\/whatsapp_image_2026_03_02_at_09_1772541362,5522.jpg\"><img decoding=\"async\" src=\"https:\/\/douradosagora.com.br\/media\/editorjs\/whatsapp_image_2026_03_02_at_09_1772541362,5522.jpg\" alt=\"\"\/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Evento ser\u00e1 realizado no Centro de Conven\u00e7\u00f5es localizado na entrada do bairro parque Alvorada &#8211; Foto: Arquivo Evento acontece de&hellip;<\/p>\n","protected":false},"author":1,"featured_media":9214,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts\/9213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/comments?post=9213"}],"version-history":[{"count":1,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts\/9213\/revisions"}],"predecessor-version":[{"id":9215,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/posts\/9213\/revisions\/9215"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/media\/9214"}],"wp:attachment":[{"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/media?parent=9213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/categories?post=9213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suanoticiaaqui.com.br\/news\/wp-json\/wp\/v2\/tags?post=9213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}